{"id":26412,"date":"2022-02-14T11:45:18","date_gmt":"2022-02-14T10:45:18","guid":{"rendered":"https:\/\/www.regner.tech\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/"},"modified":"2024-09-30T12:10:39","modified_gmt":"2024-09-30T10:10:39","slug":"barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden","status":"publish","type":"post","link":"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/","title":{"rendered":"Barduva Hebesysteme, Zuverl\u00e4ssigkeit und Komfort f\u00fcr alle Arten von Geb\u00e4uden."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"26412\" class=\"elementor elementor-26412 elementor-17202\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-402acd6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"402acd6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f20201e\" data-id=\"f20201e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-335d3b0 elementor-widget elementor-widget-template\" data-id=\"335d3b0\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"17369\" class=\"elementor elementor-17369 elementor-1195\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-1136591e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1136591e\" data-element_type=\"section\" id=\"blackheader\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-22658ac1\" data-id=\"22658ac1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-453d064f elementor-widget elementor-widget-image\" data-id=\"453d064f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.regner.tech\/de\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"620\" height=\"620\" src=\"https:\/\/www.regner.tech\/wp-content\/uploads\/2021\/09\/logo-regner-1.svg\" class=\"elementor-animation-shrink attachment-large size-large wp-image-12292\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1fa00cef\" data-id=\"1fa00cef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d25a0b6 elementor-nav-menu__align-start elementor-nav-menu--dropdown-mobile elementor-nav-menu--stretch elementor-widget__width-auto elementor-hidden-mobile elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"1d25a0b6\" data-element_type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;layout&quot;:&quot;horizontal&quot;,&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-grow\">\n\t\t\t\t<ul id=\"menu-1-1d25a0b6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-17468\"><a href=\"https:\/\/www.regner.tech\/de\/produkte\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\">Produkte<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17469\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/linearantriebe\/\" class=\"elementor-sub-item\">Linearantriebe<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17470\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/lineare-mikroantriebe\/\" class=\"elementor-sub-item\">Lineare Mikroantriebe<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17472\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/steuersysteme\/\" class=\"elementor-sub-item\">Steuersysteme<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17471\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/kundenspezifische-stellantriebe\/\" class=\"elementor-sub-item\">Kundenspezifische Stellantriebe<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17474\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/komplettloesungen-und-zubehoer\/\" class=\"elementor-sub-item\">Komplettl\u00f6sungen und Zubeh\u00f6r<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-17475\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\">Gesch\u00e4ftsbereiche<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17476\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/medizintechnik\/\" class=\"elementor-sub-item\">Medizintechnik<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17477\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/biotechnologie\/\" class=\"elementor-sub-item\">Biotechnologie<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17478\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/pharma\/\" class=\"elementor-sub-item\">Pharma<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17479\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/sonderfahrzeuge\/\" class=\"elementor-sub-item\">Sonderfahrzeuge<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17480\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/industrie\/\" class=\"elementor-sub-item\">Industrie<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17481\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/energie\/\" class=\"elementor-sub-item\">Energie<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-17482\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\">REGNER\u00ae<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17483\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/vision-mission-und-werte\/\" class=\"elementor-sub-item\">Vision, Mission und Werte<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17485\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/qualitat\/\" class=\"elementor-sub-item\">Qualit\u00e4t<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17486\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/forschung-und-entwicklung\/\" class=\"elementor-sub-item\">Forschung und Entwicklung<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17487\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/produktdeklarationen\/\" class=\"elementor-sub-item\">Produktdeklarationen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17484\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/nachhaltigkeit\/\" class=\"elementor-sub-item\">Nachhaltigkeit<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17488\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/unternehmenszertifizierungen\/\" class=\"elementor-sub-item\">Unternehmenszertifizierungen<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17489\"><a href=\"https:\/\/www.regner.tech\/de\/neuigkeiten\/\" class=\"elementor-item\">Neuigkeiten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17490\"><a href=\"https:\/\/www.regner.tech\/de\/download-seite\/\" class=\"elementor-item\">Download-Seite<\/a><\/li>\n<li class=\"tienda menu-item menu-item-type-post_type menu-item-object-page menu-item-17491\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/\" class=\"elementor-item\">Online-Shop<\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-de wpml-ls-current-language wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-has-children menu-item-wpml-ls-2-de\"><a title=\"DE\" href=\"https:\/\/www.regner.tech\/de\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\"><span class=\"wpml-ls-native\" lang=\"de\">DE<\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-es wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-2-es\"><a title=\"ES\" href=\"https:\/\/www.regner.tech\/\" class=\"elementor-sub-item\"><span class=\"wpml-ls-native\" lang=\"es\">ES<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-ca wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-2-ca\"><a title=\"CA\" href=\"https:\/\/www.regner.tech\/ca\/\" class=\"elementor-sub-item\"><span class=\"wpml-ls-native\" lang=\"ca\">CA<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-2-en\"><a title=\"EN\" href=\"https:\/\/www.regner.tech\/en\/\" class=\"elementor-sub-item\"><span class=\"wpml-ls-native\" lang=\"en\">EN<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Men\u00fc Umschalter\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Men\u00fc<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-1d25a0b6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-17468\"><a href=\"https:\/\/www.regner.tech\/de\/produkte\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\" tabindex=\"-1\">Produkte<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17469\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/linearantriebe\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Linearantriebe<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17470\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/lineare-mikroantriebe\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Lineare Mikroantriebe<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17472\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/steuersysteme\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Steuersysteme<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17471\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/kundenspezifische-stellantriebe\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Kundenspezifische Stellantriebe<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17474\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/komplettloesungen-und-zubehoer\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Komplettl\u00f6sungen und Zubeh\u00f6r<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-17475\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\" tabindex=\"-1\">Gesch\u00e4ftsbereiche<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17476\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/medizintechnik\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Medizintechnik<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17477\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/biotechnologie\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Biotechnologie<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17478\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/pharma\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Pharma<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17479\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/sonderfahrzeuge\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Sonderfahrzeuge<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17480\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/industrie\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Industrie<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17481\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/energie\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Energie<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-17482\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\" tabindex=\"-1\">REGNER\u00ae<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17483\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/vision-mission-und-werte\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Vision, Mission und Werte<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17485\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/qualitat\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Qualit\u00e4t<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17486\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/forschung-und-entwicklung\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Forschung und Entwicklung<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17487\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/produktdeklarationen\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Produktdeklarationen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17484\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/nachhaltigkeit\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Nachhaltigkeit<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17488\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/unternehmenszertifizierungen\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Unternehmenszertifizierungen<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17489\"><a href=\"https:\/\/www.regner.tech\/de\/neuigkeiten\/\" class=\"elementor-item\" tabindex=\"-1\">Neuigkeiten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17490\"><a href=\"https:\/\/www.regner.tech\/de\/download-seite\/\" class=\"elementor-item\" tabindex=\"-1\">Download-Seite<\/a><\/li>\n<li class=\"tienda menu-item menu-item-type-post_type menu-item-object-page menu-item-17491\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/\" class=\"elementor-item\" tabindex=\"-1\">Online-Shop<\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-de wpml-ls-current-language wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-has-children menu-item-wpml-ls-2-de\"><a title=\"DE\" href=\"https:\/\/www.regner.tech\/de\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\" tabindex=\"-1\"><span class=\"wpml-ls-native\" lang=\"de\">DE<\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-es wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-2-es\"><a title=\"ES\" href=\"https:\/\/www.regner.tech\/\" class=\"elementor-sub-item\" tabindex=\"-1\"><span class=\"wpml-ls-native\" lang=\"es\">ES<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-ca wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-2-ca\"><a title=\"CA\" href=\"https:\/\/www.regner.tech\/ca\/\" class=\"elementor-sub-item\" tabindex=\"-1\"><span class=\"wpml-ls-native\" lang=\"ca\">CA<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-2-en\"><a title=\"EN\" href=\"https:\/\/www.regner.tech\/en\/\" class=\"elementor-sub-item\" tabindex=\"-1\"><span class=\"wpml-ls-native\" lang=\"en\">EN<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ceaa71f\" data-id=\"ceaa71f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48bcd07 elementor-nav-menu__align-start elementor-nav-menu--dropdown-mobile elementor-nav-menu--stretch elementor-widget__width-auto elementor-hidden-tablet elementor-hidden-desktop elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"48bcd07\" data-element_type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;layout&quot;:&quot;horizontal&quot;,&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-grow\">\n\t\t\t\t<ul id=\"menu-1-48bcd07\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-17468\"><a href=\"https:\/\/www.regner.tech\/de\/produkte\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\">Produkte<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17469\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/linearantriebe\/\" class=\"elementor-sub-item\">Linearantriebe<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17470\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/lineare-mikroantriebe\/\" class=\"elementor-sub-item\">Lineare Mikroantriebe<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17472\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/steuersysteme\/\" class=\"elementor-sub-item\">Steuersysteme<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17471\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/kundenspezifische-stellantriebe\/\" class=\"elementor-sub-item\">Kundenspezifische Stellantriebe<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17474\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/komplettloesungen-und-zubehoer\/\" class=\"elementor-sub-item\">Komplettl\u00f6sungen und Zubeh\u00f6r<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-17475\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\">Gesch\u00e4ftsbereiche<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17476\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/medizintechnik\/\" class=\"elementor-sub-item\">Medizintechnik<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17477\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/biotechnologie\/\" class=\"elementor-sub-item\">Biotechnologie<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17478\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/pharma\/\" class=\"elementor-sub-item\">Pharma<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17479\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/sonderfahrzeuge\/\" class=\"elementor-sub-item\">Sonderfahrzeuge<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17480\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/industrie\/\" class=\"elementor-sub-item\">Industrie<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17481\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/energie\/\" class=\"elementor-sub-item\">Energie<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-17482\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\">REGNER\u00ae<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17483\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/vision-mission-und-werte\/\" class=\"elementor-sub-item\">Vision, Mission und Werte<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17485\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/qualitat\/\" class=\"elementor-sub-item\">Qualit\u00e4t<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17486\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/forschung-und-entwicklung\/\" class=\"elementor-sub-item\">Forschung und Entwicklung<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17487\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/produktdeklarationen\/\" class=\"elementor-sub-item\">Produktdeklarationen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17484\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/nachhaltigkeit\/\" class=\"elementor-sub-item\">Nachhaltigkeit<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17488\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/unternehmenszertifizierungen\/\" class=\"elementor-sub-item\">Unternehmenszertifizierungen<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17489\"><a href=\"https:\/\/www.regner.tech\/de\/neuigkeiten\/\" class=\"elementor-item\">Neuigkeiten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17490\"><a href=\"https:\/\/www.regner.tech\/de\/download-seite\/\" class=\"elementor-item\">Download-Seite<\/a><\/li>\n<li class=\"tienda menu-item menu-item-type-post_type menu-item-object-page menu-item-17491\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/\" class=\"elementor-item\">Online-Shop<\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-de wpml-ls-current-language wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-has-children menu-item-wpml-ls-2-de\"><a title=\"DE\" href=\"https:\/\/www.regner.tech\/de\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\"><span class=\"wpml-ls-native\" lang=\"de\">DE<\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-es wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-2-es\"><a title=\"ES\" href=\"https:\/\/www.regner.tech\/\" class=\"elementor-sub-item\"><span class=\"wpml-ls-native\" lang=\"es\">ES<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-ca wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-2-ca\"><a title=\"CA\" href=\"https:\/\/www.regner.tech\/ca\/\" class=\"elementor-sub-item\"><span class=\"wpml-ls-native\" lang=\"ca\">CA<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-2-en\"><a title=\"EN\" href=\"https:\/\/www.regner.tech\/en\/\" class=\"elementor-sub-item\"><span class=\"wpml-ls-native\" lang=\"en\">EN<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Men\u00fc Umschalter\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Men\u00fc<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-48bcd07\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-17468\"><a href=\"https:\/\/www.regner.tech\/de\/produkte\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\" tabindex=\"-1\">Produkte<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17469\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/linearantriebe\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Linearantriebe<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17470\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/lineare-mikroantriebe\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Lineare Mikroantriebe<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17472\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/steuersysteme\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Steuersysteme<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17471\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/kundenspezifische-stellantriebe\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Kundenspezifische Stellantriebe<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17474\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/komplettloesungen-und-zubehoer\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Komplettl\u00f6sungen und Zubeh\u00f6r<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-17475\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\" tabindex=\"-1\">Gesch\u00e4ftsbereiche<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17476\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/medizintechnik\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Medizintechnik<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17477\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/biotechnologie\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Biotechnologie<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17478\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/pharma\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Pharma<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17479\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/sonderfahrzeuge\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Sonderfahrzeuge<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17480\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/industrie\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Industrie<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17481\"><a href=\"https:\/\/www.regner.tech\/de\/geschaeftsbereiche\/energie\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Energie<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-17482\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\" tabindex=\"-1\">REGNER\u00ae<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17483\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/vision-mission-und-werte\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Vision, Mission und Werte<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17485\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/qualitat\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Qualit\u00e4t<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17486\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/forschung-und-entwicklung\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Forschung und Entwicklung<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17487\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/produktdeklarationen\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Produktdeklarationen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17484\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/nachhaltigkeit\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Nachhaltigkeit<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17488\"><a href=\"https:\/\/www.regner.tech\/de\/regner\/unternehmenszertifizierungen\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Unternehmenszertifizierungen<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17489\"><a href=\"https:\/\/www.regner.tech\/de\/neuigkeiten\/\" class=\"elementor-item\" tabindex=\"-1\">Neuigkeiten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17490\"><a href=\"https:\/\/www.regner.tech\/de\/download-seite\/\" class=\"elementor-item\" tabindex=\"-1\">Download-Seite<\/a><\/li>\n<li class=\"tienda menu-item menu-item-type-post_type menu-item-object-page menu-item-17491\"><a href=\"https:\/\/www.regner.tech\/de\/shop\/\" class=\"elementor-item\" tabindex=\"-1\">Online-Shop<\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-de wpml-ls-current-language wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-has-children menu-item-wpml-ls-2-de\"><a title=\"DE\" href=\"https:\/\/www.regner.tech\/de\/\" aria-haspopup=\"true\" aria-expanded=\"false\" class=\"elementor-item\" tabindex=\"-1\"><span class=\"wpml-ls-native\" lang=\"de\">DE<\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-es wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-2-es\"><a title=\"ES\" href=\"https:\/\/www.regner.tech\/\" class=\"elementor-sub-item\" tabindex=\"-1\"><span class=\"wpml-ls-native\" lang=\"es\">ES<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-ca wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-2-ca\"><a title=\"CA\" href=\"https:\/\/www.regner.tech\/ca\/\" class=\"elementor-sub-item\" tabindex=\"-1\"><span class=\"wpml-ls-native\" lang=\"ca\">CA<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-2 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-2-en\"><a title=\"EN\" href=\"https:\/\/www.regner.tech\/en\/\" class=\"elementor-sub-item\" tabindex=\"-1\"><span class=\"wpml-ls-native\" lang=\"en\">EN<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-889d56b elementor-widget__width-auto elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"889d56b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.regner.tech\/de\/kontakt\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontakt<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bf13f5 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"3bf13f5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.regner.tech\/mi-cuenta\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"242\" height=\"248\" src=\"https:\/\/www.regner.tech\/wp-content\/uploads\/2021\/09\/login-black.svg\" class=\"attachment-large size-large wp-image-12137\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef362eb toggle-icon--bag-medium elementor-menu-cart--empty-indicator-hide elementor-widget__width-auto elementor-menu-cart--items-indicator-bubble elementor-menu-cart--cart-type-side-cart elementor-menu-cart--show-remove-button-yes elementor-widget elementor-widget-woocommerce-menu-cart\" data-id=\"ef362eb\" data-element_type=\"widget\" data-settings=\"{&quot;cart_type&quot;:&quot;side-cart&quot;,&quot;open_cart&quot;:&quot;click&quot;}\" data-widget_type=\"woocommerce-menu-cart.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-menu-cart__wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-cart__toggle_wrapper\">\n\t\t\t\t\t<div class=\"elementor-menu-cart__container elementor-lightbox\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"elementor-menu-cart__main\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-menu-cart__close-button\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"widget_shopping_cart_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-menu-cart__toggle elementor-button-wrapper\">\n\t\t\t<a id=\"elementor-menu-cart__toggle_button\" href=\"#\" class=\"elementor-menu-cart__toggle_button elementor-button elementor-size-sm\" aria-expanded=\"false\">\n\t\t\t\t<span class=\"elementor-button-text\"><span class=\"woocommerce-Price-amount amount\"><bdi>0,00<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/span>\n\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t<span class=\"elementor-button-icon-qty\" data-counter=\"0\">0<\/span>\n\t\t\t\t\t<i class=\"eicon-bag-medium\"><\/i>\t\t\t\t\t<span class=\"elementor-screen-only\">Warenkorb<\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div> <!-- close elementor-menu-cart__wrapper -->\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-19e243f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19e243f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8125b15\" data-id=\"8125b15\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40b1209 animated-slow elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"40b1209\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Barduva Hebesysteme, Zuverl\u00e4ssigkeit und Komfort f\u00fcr alle Arten von Geb\u00e4uden.<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b1427c5\" data-id=\"b1427c5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-b775e50 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"b775e50\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-29c811c\" data-id=\"29c811c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1cb022 elementor-widget elementor-widget-heading\" data-id=\"d1cb022\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Regner\u00ae Editorial Team<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e400487 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"e400487\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aiguaviva - <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4aedc96 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4aedc96\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">14\/02\/2022<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4da7e53 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4da7e53\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d6d5f6\" data-id=\"7d6d5f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3571620 elementor-widget elementor-widget-image\" data-id=\"3571620\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.regner.tech\/wp-content\/uploads\/elementor\/thumbs\/foto03-1536x576-1-powh672rbk1djr9tqy8dacpwc3icbcw11hi8492h40.jpg\" title=\"foto03-1536&#215;576\" alt=\"foto03-1536x576\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-572ec14 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"572ec14\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ea305d0\" data-id=\"ea305d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2808aa2 elementor-widget elementor-widget-text-editor\" data-id=\"2808aa2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>1968 erlie\u00df US-Pr\u00e4sident Lyndon B. Johnson den<em> Architectural Barriers Act,<\/em> einen der ersten Versuche, bestimmte Geb\u00e4ude und Einrichtungen mit Bundesmitteln so zu bauen, dass sie f\u00fcr Menschen mit eingeschr\u00e4nkter Mobilit\u00e4t zug\u00e4nglich sind. Dieser Begriff des \u201e<strong>Rechts auf Stadt<\/strong>\u201c ist eng mit der Idee der \u201eSt\u00e4dte f\u00fcr alle\u201c verbunden und f\u00fchrt das Postulat der <strong> <\/strong>universelle Zug\u00e4nglichkeit, die durch \u201euniverselles Design\u201c R\u00e4ume und Produkte schafft, die den Bed\u00fcrfnissen m\u00f6glichst vieler Menschen entsprechen.<\/p>\n<\/p>\n<p>So wie die Gestaltung der Umgebungen und R\u00e4ume, in denen wir uns bewegen, soziale Interaktion behindern oder f\u00f6rdern kann, kann sie auch Formen der Integration von Menschen mit Behinderungen ausgrenzen oder schaffen, mit den entsprechenden physischen, wirtschaftlichen oder sozialen Auswirkungen.<\/p>\n<\/p>\n<p>Ausgrenzung kann den Zugang der Menschen zu angemessener Bildung und Gesundheit, ihre Integration in den <strong>Arbeitsmarkt und sogar ihre Teilnahme am gesellschaftlichen Leben einschr\u00e4nken. Umgekehrt erm\u00f6glicht universelles Design, das ein integratives Umfeld f\u00f6rdert, allen B\u00fcrgern, sich frei und selbst\u00e4ndig zu bewegen,<\/strong> und <strong>tr\u00e4gt <\/strong>damit indirekt zur Verbesserung der Lebensqualit\u00e4t anderer bei. <\/p>\n<\/p>\n<p>Wenn von Barrierefreiheit die Rede ist, bezieht sich dies in den meisten F\u00e4llen auf Menschen mit eingeschr\u00e4nkter Mobilit\u00e4t. Es ist jedoch notwendig, den Begriff weiter zu fassen, denn jeder hat das <strong>Recht auf eine zug\u00e4ngliche Umgebung, so dass die B\u00fcrger unabh\u00e4ngig von ihrer k\u00f6rperlichen Verfassung Dienstleistungen und Produkte in Anspruch nehmen k\u00f6nnen. Zu diesem Zweck muss die<\/strong> Architektur das Umfeld von St\u00e4dten und Geb\u00e4uden unter dem Gesichtspunkt eines Designs f\u00fcr alle betrachten. <\/p><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1974851\" data-id=\"1974851\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de32b60 elementor-widget elementor-widget-image\" data-id=\"de32b60\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"620\" height=\"279\" src=\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/02\/BARDUVA-LOGO-1.jpg\" class=\"attachment-large size-large wp-image-17214\" alt=\"\" srcset=\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/02\/BARDUVA-LOGO-1.jpg 768w, https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/02\/BARDUVA-LOGO-1-300x135.jpg 300w, https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/02\/BARDUVA-LOGO-1-750x337.jpg 750w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-241a8f8 elementor-widget elementor-widget-text-editor\" data-id=\"241a8f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-has-fill\">\n<div class=\"vc_column-inner vc_custom_1627851513801\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Das 1996 in Vilnius gegr\u00fcndete litauische <strong>Unternehmen Barduva bietet eine breite Palette von L\u00f6sungen f\u00fcr die Barrierefreiheit zu Hause, in Gesch\u00e4ften, \u00f6ffentlichen Einrichtungen und B\u00fcros.<\/strong> <\/p>\n<p>Das Unternehmen ist auf die Entwicklung und Herstellung von vertikalen Plattformliften und offenen Plattformliften spezialisiert.<\/p>\n<\/p>\n<\/div>\n<div class=\"wpb_wrapper\">\n<p>Die technische Abteilung von Barduva entwickelt jedes Projekt und passt es an die vorhandenen R\u00e4umlichkeiten an. Die Techniker von Barduva zeichnen sich durch ihre gro\u00dfe Erfahrung und ihr Wissen \u00fcber die neuesten Trends im Bereich der Barrierefreiheit aus. <\/p>\n<\/p>\n<p>Neben der breiten Palette an Produkten und <strong>Dienstleistungen zeichnet sich Barduva durch seinen individuellen technischen Service f\u00fcr Projekte aus,<\/strong> die ein vollst\u00e4ndig ma\u00dfgeschneidertes Produkt erfordern. Barduva hat vor allem dank seines verantwortungsvollen und professionellen Teams, das sich nicht scheut, gr\u00f6\u00dfere Verantwortung zu \u00fcbernehmen und interessante und herausfordernde Projekte umzusetzen, eine gro\u00dfe betriebliche Effizienz erreicht. <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-eba9d47 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eba9d47\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2646310\" data-id=\"2646310\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-773a0da elementor-widget elementor-widget-heading\" data-id=\"773a0da\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BARDUVA Plattformen werden ger\u00e4uschlos mit dem RA-47 Antrieb angehoben.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-bef05ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bef05ad\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-409d793\" data-id=\"409d793\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93b223c elementor-widget elementor-widget-image\" data-id=\"93b223c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"465\" src=\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/02\/foto01.jpg\" class=\"attachment-large size-large wp-image-17225\" alt=\"\" srcset=\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/02\/foto01.jpg 800w, https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/02\/foto01-300x225.jpg 300w, https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/02\/foto01-768x576.jpg 768w, https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/02\/foto01-750x563.jpg 750w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c447616\" data-id=\"c447616\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ef3124 elementor-widget elementor-widget-image\" data-id=\"6ef3124\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"465\" src=\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/02\/foto02.jpg\" class=\"attachment-large size-large wp-image-17228\" alt=\"\" srcset=\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/02\/foto02.jpg 800w, https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/02\/foto02-300x225.jpg 300w, https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/02\/foto02-768x576.jpg 768w, https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/02\/foto02-750x563.jpg 750w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-9f04d1d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f04d1d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6628d9b\" data-id=\"6628d9b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ba5d36 elementor-widget elementor-widget-text-editor\" data-id=\"4ba5d36\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Treppenlifte sind zweifelsohne die perfekte L\u00f6sung, um die Zug\u00e4nglichkeit f\u00fcr Rollstuhlfahrer zu gew\u00e4hrleisten. Bei diesen Plattformen handelt es sich um Hebesysteme, die f\u00fcr den Einbau in \u00f6ffentliche oder private R\u00e4ume konzipiert sind, sei es im Innen- oder Au\u00dfenbereich, mit dem Ziel, die vertikale Bewegung f\u00fcr Menschen mit eingeschr\u00e4nkter Mobilit\u00e4t zu erleichtern. Wenn es um Treppenlifte f\u00fcr Menschen mit eingeschr\u00e4nkter Mobilit\u00e4t geht, wei\u00df B<strong>arduva um die Notwendigkeit von sicheren und zuverl\u00e4ssigen Antrieben, die Tag f\u00fcr Tag<\/strong> <strong>funktionieren<\/strong>. Der Linearantrieb RA-47 von REGNER<sup>\u00ae<\/sup> ist die ideale Wahl f\u00fcr die Hersteller dieser Art von Liftsystemen.  <\/p>\n<\/p>\n<p>Die <strong>Verwendung des elektrischen <\/strong><strong>REGNER<sup>\u00ae<\/sup> RA-47-Antriebs f\u00fcr Treppenlifte bietet Robustheit und St\u00e4rke in einem kompakten Design.<\/strong> Der RA-47 ist ein Linearantrieb mit einer Hubkraft von bis zu 2.500N, der f\u00fcr Erstausr\u00fcster bestimmt ist. Der neue Motor bietet eine hervorragende Leistung, eine lange Lebensdauer und einen niedrigen Energieverbrauch. Mit dem RA-47 steht den Herstellern ein hocheffizienter Antrieb zur Verf\u00fcgung.   <\/p>\n<\/p>\n<p>Der RA-47 bietet sich f\u00fcr Treppenlifte und \u00e4hnliche Hebesysteme an:<\/p>\n<\/p>\n<p>&#8211; Optimierte <strong>Ergonomie <\/strong>mit hohem Komfort<br \/>&#8211; <strong>Ger\u00e4uscharme Bewegung<\/strong> in einem kompakten Design<br \/>&#8211; Ein <strong>\u00e4u\u00dferst zuverl\u00e4ssiger<\/strong> Aktuator, <strong>der die geltenden Normen und Vorschriften erf\u00fcllt und die Hersteller bei ihren Zulassungsprozessen unterst\u00fctzt<\/strong>, da er \u00fcber alle relevanten Zertifizierungen verf\u00fcgt.<\/p>\n<\/p>\n<p>Mit dem RA-47-Antrieb k\u00f6nnen Hersteller Treppenlifte anbieten, die sich an alle Arten von R\u00e4umen anpassen lassen.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-8a21d7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a21d7f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f5d35c8\" data-id=\"f5d35c8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac0d75a elementor-widget elementor-widget-heading\" data-id=\"ac0d75a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bitte teilen Sie diesen Artikel!<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ada302 elementor-share-buttons--view-icon elementor-share-buttons--skin-flat elementor-share-buttons--align-center elementor-share-buttons--color-custom elementor-share-buttons--shape-circle elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"4ada302\" data-element_type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-grid\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_twitter\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Teilen auf twitter\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_facebook\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Teilen auf facebook\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_linkedin\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Teilen auf linkedin\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Die Benutzer der Hebeb\u00fchnen von Barduva k\u00f6nnen ihren Komfort dank des RA-47 genie\u00dfen, einem Antrieb mit leisen Bewegungen, geringem Energieverbrauch und langer Lebensdauer.<\/p>\n","protected":false},"author":2,"featured_media":17205,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[96],"tags":[],"class_list":["post-26412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anwendungen-und-losungen","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Barduva Hebesysteme, Zuverl\u00e4ssigkeit und Komfort f\u00fcr alle Arten von Geb\u00e4uden. | REGNER<\/title>\n<meta name=\"description\" content=\"Die Benutzer der Hebeb\u00fchnen von Barduva k\u00f6nnen ihren Komfort dank des RA-47 genie\u00dfen, einem Antrieb mit leisen Bewegungen, geringem Energieverbrauch und langer Lebensdauer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barduva Hebesysteme, Zuverl\u00e4ssigkeit und Komfort f\u00fcr alle Arten von Geb\u00e4uden. | REGNER\" \/>\n<meta property=\"og:description\" content=\"Die Benutzer der Hebeb\u00fchnen von Barduva k\u00f6nnen ihren Komfort dank des RA-47 genie\u00dfen, einem Antrieb mit leisen Bewegungen, geringem Energieverbrauch und langer Lebensdauer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/\" \/>\n<meta property=\"og:site_name\" content=\"REGNER\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-14T10:45:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-30T10:10:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/04\/foto03-1536x576-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"regner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"regner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/\"},\"author\":{\"name\":\"regner\",\"@id\":\"https:\/\/www.regner.tech\/de\/#\/schema\/person\/8f0944ac4fed6804a617068fcf7d7990\"},\"headline\":\"Barduva Hebesysteme, Zuverl\u00e4ssigkeit und Komfort f\u00fcr alle Arten von Geb\u00e4uden.\",\"datePublished\":\"2022-02-14T10:45:18+00:00\",\"dateModified\":\"2024-09-30T10:10:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/\"},\"wordCount\":686,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.regner.tech\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/04\/foto03-1536x576-1.jpg\",\"articleSection\":[\"Anwendungen und L\u00f6sungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/\",\"url\":\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/\",\"name\":\"Barduva Hebesysteme, Zuverl\u00e4ssigkeit und Komfort f\u00fcr alle Arten von Geb\u00e4uden. | REGNER\",\"isPartOf\":{\"@id\":\"https:\/\/www.regner.tech\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/04\/foto03-1536x576-1.jpg\",\"datePublished\":\"2022-02-14T10:45:18+00:00\",\"dateModified\":\"2024-09-30T10:10:39+00:00\",\"description\":\"Die Benutzer der Hebeb\u00fchnen von Barduva k\u00f6nnen ihren Komfort dank des RA-47 genie\u00dfen, einem Antrieb mit leisen Bewegungen, geringem Energieverbrauch und langer Lebensdauer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#primaryimage\",\"url\":\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/04\/foto03-1536x576-1.jpg\",\"contentUrl\":\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/04\/foto03-1536x576-1.jpg\",\"width\":1536,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.regner.tech\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barduva Hebesysteme, Zuverl\u00e4ssigkeit und Komfort f\u00fcr alle Arten von Geb\u00e4uden.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.regner.tech\/de\/#website\",\"url\":\"https:\/\/www.regner.tech\/de\/\",\"name\":\"REGNER\",\"description\":\"Soluciones avanzadas de movimiento lineal\",\"publisher\":{\"@id\":\"https:\/\/www.regner.tech\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.regner.tech\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.regner.tech\/de\/#organization\",\"name\":\"REGNER\u00ae\",\"url\":\"https:\/\/www.regner.tech\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.regner.tech\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/05\/skin07s.header-logo-hd.png\",\"contentUrl\":\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/05\/skin07s.header-logo-hd.png\",\"width\":292,\"height\":56,\"caption\":\"REGNER\u00ae\"},\"image\":{\"@id\":\"https:\/\/www.regner.tech\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.regner.tech\/de\/#\/schema\/person\/8f0944ac4fed6804a617068fcf7d7990\",\"name\":\"regner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.regner.tech\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f7d674ef46047306287ebc40bcd8647c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f7d674ef46047306287ebc40bcd8647c?s=96&d=mm&r=g\",\"caption\":\"regner\"},\"url\":\"https:\/\/www.regner.tech\/de\/author\/regner\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barduva Hebesysteme, Zuverl\u00e4ssigkeit und Komfort f\u00fcr alle Arten von Geb\u00e4uden. | REGNER","description":"Die Benutzer der Hebeb\u00fchnen von Barduva k\u00f6nnen ihren Komfort dank des RA-47 genie\u00dfen, einem Antrieb mit leisen Bewegungen, geringem Energieverbrauch und langer Lebensdauer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/","og_locale":"de_DE","og_type":"article","og_title":"Barduva Hebesysteme, Zuverl\u00e4ssigkeit und Komfort f\u00fcr alle Arten von Geb\u00e4uden. | REGNER","og_description":"Die Benutzer der Hebeb\u00fchnen von Barduva k\u00f6nnen ihren Komfort dank des RA-47 genie\u00dfen, einem Antrieb mit leisen Bewegungen, geringem Energieverbrauch und langer Lebensdauer.","og_url":"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/","og_site_name":"REGNER","article_published_time":"2022-02-14T10:45:18+00:00","article_modified_time":"2024-09-30T10:10:39+00:00","og_image":[{"width":1536,"height":576,"url":"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/04\/foto03-1536x576-1.jpg","type":"image\/jpeg"}],"author":"regner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"regner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#article","isPartOf":{"@id":"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/"},"author":{"name":"regner","@id":"https:\/\/www.regner.tech\/de\/#\/schema\/person\/8f0944ac4fed6804a617068fcf7d7990"},"headline":"Barduva Hebesysteme, Zuverl\u00e4ssigkeit und Komfort f\u00fcr alle Arten von Geb\u00e4uden.","datePublished":"2022-02-14T10:45:18+00:00","dateModified":"2024-09-30T10:10:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/"},"wordCount":686,"commentCount":0,"publisher":{"@id":"https:\/\/www.regner.tech\/de\/#organization"},"image":{"@id":"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/04\/foto03-1536x576-1.jpg","articleSection":["Anwendungen und L\u00f6sungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/","url":"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/","name":"Barduva Hebesysteme, Zuverl\u00e4ssigkeit und Komfort f\u00fcr alle Arten von Geb\u00e4uden. | REGNER","isPartOf":{"@id":"https:\/\/www.regner.tech\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#primaryimage"},"image":{"@id":"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/04\/foto03-1536x576-1.jpg","datePublished":"2022-02-14T10:45:18+00:00","dateModified":"2024-09-30T10:10:39+00:00","description":"Die Benutzer der Hebeb\u00fchnen von Barduva k\u00f6nnen ihren Komfort dank des RA-47 genie\u00dfen, einem Antrieb mit leisen Bewegungen, geringem Energieverbrauch und langer Lebensdauer.","breadcrumb":{"@id":"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#primaryimage","url":"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/04\/foto03-1536x576-1.jpg","contentUrl":"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/04\/foto03-1536x576-1.jpg","width":1536,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/www.regner.tech\/de\/barduva-hebesysteme-zuverlaessigkeit-und-komfort-fuer-alle-arten-von-gebaeuden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.regner.tech\/de\/"},{"@type":"ListItem","position":2,"name":"Barduva Hebesysteme, Zuverl\u00e4ssigkeit und Komfort f\u00fcr alle Arten von Geb\u00e4uden."}]},{"@type":"WebSite","@id":"https:\/\/www.regner.tech\/de\/#website","url":"https:\/\/www.regner.tech\/de\/","name":"REGNER","description":"Soluciones avanzadas de movimiento lineal","publisher":{"@id":"https:\/\/www.regner.tech\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.regner.tech\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.regner.tech\/de\/#organization","name":"REGNER\u00ae","url":"https:\/\/www.regner.tech\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.regner.tech\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/05\/skin07s.header-logo-hd.png","contentUrl":"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/05\/skin07s.header-logo-hd.png","width":292,"height":56,"caption":"REGNER\u00ae"},"image":{"@id":"https:\/\/www.regner.tech\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.regner.tech\/de\/#\/schema\/person\/8f0944ac4fed6804a617068fcf7d7990","name":"regner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.regner.tech\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f7d674ef46047306287ebc40bcd8647c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7d674ef46047306287ebc40bcd8647c?s=96&d=mm&r=g","caption":"regner"},"url":"https:\/\/www.regner.tech\/de\/author\/regner\/"}]}},"_links":{"self":[{"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/posts\/26412"}],"collection":[{"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/comments?post=26412"}],"version-history":[{"count":1,"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/posts\/26412\/revisions"}],"predecessor-version":[{"id":26413,"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/posts\/26412\/revisions\/26413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/media\/17205"}],"wp:attachment":[{"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/media?parent=26412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/categories?post=26412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/tags?post=26412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}