{"id":96,"count":66,"description":"","link":"https:\/\/www.regner.tech\/de\/category\/anwendungen-und-losungen\/","name":"Anwendungen und L\u00f6sungen","slug":"anwendungen-und-losungen","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Anwendungen und L\u00f6sungen | REGNER<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.regner.tech\/de\/category\/anwendungen-und-losungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anwendungen und L\u00f6sungen | REGNER\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.regner.tech\/de\/category\/anwendungen-und-losungen\/\" \/>\n<meta property=\"og:site_name\" content=\"REGNER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.regner.tech\/de\/category\/anwendungen-und-losungen\/\",\"url\":\"https:\/\/www.regner.tech\/de\/category\/anwendungen-und-losungen\/\",\"name\":\"Anwendungen und L\u00f6sungen | REGNER\",\"isPartOf\":{\"@id\":\"https:\/\/www.regner.tech\/de\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.regner.tech\/de\/category\/anwendungen-und-losungen\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.regner.tech\/de\/category\/anwendungen-und-losungen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.regner.tech\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anwendungen und L\u00f6sungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.regner.tech\/de\/#website\",\"url\":\"https:\/\/www.regner.tech\/de\/\",\"name\":\"REGNER\",\"description\":\"Soluciones avanzadas de movimiento lineal\",\"publisher\":{\"@id\":\"https:\/\/www.regner.tech\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.regner.tech\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.regner.tech\/de\/#organization\",\"name\":\"REGNER\u00ae\",\"url\":\"https:\/\/www.regner.tech\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.regner.tech\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/05\/skin07s.header-logo-hd.png\",\"contentUrl\":\"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/05\/skin07s.header-logo-hd.png\",\"width\":292,\"height\":56,\"caption\":\"REGNER\u00ae\"},\"image\":{\"@id\":\"https:\/\/www.regner.tech\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anwendungen und L\u00f6sungen | REGNER","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.regner.tech\/de\/category\/anwendungen-und-losungen\/","og_locale":"de_DE","og_type":"article","og_title":"Anwendungen und L\u00f6sungen | REGNER","og_url":"https:\/\/www.regner.tech\/de\/category\/anwendungen-und-losungen\/","og_site_name":"REGNER","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.regner.tech\/de\/category\/anwendungen-und-losungen\/","url":"https:\/\/www.regner.tech\/de\/category\/anwendungen-und-losungen\/","name":"Anwendungen und L\u00f6sungen | REGNER","isPartOf":{"@id":"https:\/\/www.regner.tech\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.regner.tech\/de\/category\/anwendungen-und-losungen\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.regner.tech\/de\/category\/anwendungen-und-losungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.regner.tech\/de\/"},{"@type":"ListItem","position":2,"name":"Anwendungen und L\u00f6sungen"}]},{"@type":"WebSite","@id":"https:\/\/www.regner.tech\/de\/#website","url":"https:\/\/www.regner.tech\/de\/","name":"REGNER","description":"Soluciones avanzadas de movimiento lineal","publisher":{"@id":"https:\/\/www.regner.tech\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.regner.tech\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.regner.tech\/de\/#organization","name":"REGNER\u00ae","url":"https:\/\/www.regner.tech\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.regner.tech\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/05\/skin07s.header-logo-hd.png","contentUrl":"https:\/\/www.regner.tech\/wp-content\/uploads\/2022\/05\/skin07s.header-logo-hd.png","width":292,"height":56,"caption":"REGNER\u00ae"},"image":{"@id":"https:\/\/www.regner.tech\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/categories\/96"}],"collection":[{"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.regner.tech\/de\/wp-json\/wp\/v2\/posts?categories=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}